{"id":279103,"date":"2026-04-13T19:52:57","date_gmt":"2026-04-13T12:52:57","guid":{"rendered":"https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1.jpg"},"modified":"2026-04-13T19:53:16","modified_gmt":"2026-04-13T12:53:16","slug":"6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1","status":"inherit","type":"attachment","link":"https:\/\/nawacita.co\/index.php\/2026\/04\/13\/tentara-israel-rusak-fasilitas-keamanan-pbb-tank-sengaja-tabrak-kendaraan-unifil\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1\/","title":{"rendered":"Tentara Israel Rusak Fasilitas Keamanan PBB, Tank Sengaja Tabrak Kendaraan UNIFIL."},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-279103","attachment","type-attachment","status-inherit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>nawacita<\/title>\n<meta name=\"description\" content=\"nawacita\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"nawacita\" \/>\n<meta property=\"og:description\" content=\"nawacita\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Nawacita\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nawacitaco-1763136813898723\/?ref=aymt_homepage_panel\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-13T12:53:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"641\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@nawacit4\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1.jpg\",\"url\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1.jpg\",\"name\":\"nawacita\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nawacita.co\\\/#website\"},\"datePublished\":\"2026-04-13T12:52:57+00:00\",\"dateModified\":\"2026-04-13T12:53:16+00:00\",\"description\":\"nawacita\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nawacita.co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tentara Israel Rusak Fasilitas Keamanan PBB, Tank Sengaja Tabrak Kendaraan UNIFIL\",\"item\":\"https:\\\/\\\/nawacita.co\\\/index.php\\\/2026\\\/04\\\/13\\\/tentara-israel-rusak-fasilitas-keamanan-pbb-tank-sengaja-tabrak-kendaraan-unifil\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tentara Israel Rusak Fasilitas Keamanan PBB, Tank Sengaja Tabrak Kendaraan UNIFIL.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nawacita.co\\\/#website\",\"url\":\"https:\\\/\\\/nawacita.co\\\/\",\"name\":\"Nawacita\",\"description\":\"Berita Kementerian, BUMN, Pemerintah dan Politik\",\"publisher\":{\"@id\":\"https:\\\/\\\/nawacita.co\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nawacita.co\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nawacita.co\\\/#organization\",\"name\":\"Nawacita\",\"url\":\"https:\\\/\\\/nawacita.co\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/nawacita.co\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Logo-Nawacita-2021.png\",\"contentUrl\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Logo-Nawacita-2021.png\",\"width\":1676,\"height\":422,\"caption\":\"Nawacita\"},\"image\":{\"@id\":\"https:\\\/\\\/nawacita.co\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/nawacitaco-1763136813898723\\\/?ref=aymt_homepage_panel\",\"https:\\\/\\\/x.com\\\/nawacit4\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"nawacita","description":"nawacita","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1.jpg","og_locale":"en_US","og_type":"article","og_title":"nawacita","og_description":"nawacita","og_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1.jpg","og_site_name":"Nawacita","article_publisher":"https:\/\/www.facebook.com\/nawacitaco-1763136813898723\/?ref=aymt_homepage_panel","article_modified_time":"2026-04-13T12:53:16+00:00","og_image":[{"width":641,"height":400,"url":"https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@nawacit4","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1.jpg","url":"https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1.jpg","name":"nawacita","isPartOf":{"@id":"https:\/\/nawacita.co\/#website"},"datePublished":"2026-04-13T12:52:57+00:00","dateModified":"2026-04-13T12:53:16+00:00","description":"nawacita","breadcrumb":{"@id":"https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nawacita.co\/"},{"@type":"ListItem","position":2,"name":"Tentara Israel Rusak Fasilitas Keamanan PBB, Tank Sengaja Tabrak Kendaraan UNIFIL","item":"https:\/\/nawacita.co\/index.php\/2026\/04\/13\/tentara-israel-rusak-fasilitas-keamanan-pbb-tank-sengaja-tabrak-kendaraan-unifil\/"},{"@type":"ListItem","position":3,"name":"Tentara Israel Rusak Fasilitas Keamanan PBB, Tank Sengaja Tabrak Kendaraan UNIFIL."}]},{"@type":"WebSite","@id":"https:\/\/nawacita.co\/#website","url":"https:\/\/nawacita.co\/","name":"Nawacita","description":"Berita Kementerian, BUMN, Pemerintah dan Politik","publisher":{"@id":"https:\/\/nawacita.co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nawacita.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/nawacita.co\/#organization","name":"Nawacita","url":"https:\/\/nawacita.co\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nawacita.co\/#\/schema\/logo\/image\/","url":"https:\/\/nawacita.co\/wp-content\/uploads\/2021\/10\/Logo-Nawacita-2021.png","contentUrl":"https:\/\/nawacita.co\/wp-content\/uploads\/2021\/10\/Logo-Nawacita-2021.png","width":1676,"height":422,"caption":"Nawacita"},"image":{"@id":"https:\/\/nawacita.co\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nawacitaco-1763136813898723\/?ref=aymt_homepage_panel","https:\/\/x.com\/nawacit4"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"187\" src=\"https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-300x187.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-300x187.jpg 300w, https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1.jpg 641w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Tentara Israel Rusak Fasilitas Keamanan PBB, Tank Sengaja Tabrak Kendaraan UNIFIL.<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":641,"height":400,"file":"2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1.jpg","filesize":48482,"sizes":{"medium":{"file":"6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-300x187.jpg","width":300,"height":187,"filesize":14895,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-300x187.jpg"},"thumbnail":{"file":"6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-150x150.jpg","width":150,"height":150,"filesize":6577,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-150x150.jpg"},"td_80x60":{"file":"6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-80x60.jpg","width":80,"height":60,"filesize":2030,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-80x60.jpg"},"td_218x150":{"file":"6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-218x150.jpg","width":218,"height":150,"filesize":9381,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-218x150.jpg"},"td_324x400":{"file":"6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-324x400.jpg","width":324,"height":400,"filesize":28039,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-324x400.jpg"},"td_485x360":{"file":"6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-485x360.jpg","width":485,"height":360,"filesize":36446,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-485x360.jpg"},"td_100x70":{"file":"6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-100x70.jpg","width":100,"height":70,"filesize":2732,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-100x70.jpg"},"td_265x198":{"file":"6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-265x198.jpg","width":265,"height":198,"filesize":13724,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-265x198.jpg"},"td_324x160":{"file":"6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-324x160.jpg","width":324,"height":160,"filesize":13686,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-324x160.jpg"},"td_324x235":{"file":"6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-324x235.jpg","width":324,"height":235,"filesize":18655,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-324x235.jpg"},"td_356x220":{"file":"6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-356x220.jpg","width":356,"height":220,"filesize":19691,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-356x220.jpg"},"td_356x364":{"file":"6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-356x364.jpg","width":356,"height":364,"filesize":27203,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-356x364.jpg"},"td_533x261":{"file":"6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-533x261.jpg","width":533,"height":261,"filesize":30563,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-533x261.jpg"},"td_534x462":{"file":"6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-534x400.jpg","width":534,"height":400,"filesize":46602,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-534x400.jpg"},"td_696x385":{"file":"6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-641x385.jpg","width":641,"height":385,"filesize":51441,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1-641x385.jpg"},"full":{"file":"6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1.jpg","width":641,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":279101,"source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2026\/04\/6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1.jpg","filename":"6707cdc70f7de-viva-militer-pasukan-sementara-pbb-di-lebanon-unifil_663_372-1.jpg","filesize":48482,"_links":{"self":[{"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/media\/279103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/comments?post=279103"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":279101,"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/posts\/279101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}