{"id":199760,"date":"2024-02-12T17:46:52","date_gmt":"2024-02-12T10:46:52","guid":{"rendered":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya.jpg"},"modified":"2024-02-12T17:46:52","modified_gmt":"2024-02-12T10:46:52","slug":"wadan-puspenerbal-hadiri-penyerahan-monjaya","status":"inherit","type":"attachment","link":"https:\/\/nawacita.co\/index.php\/2024\/02\/12\/wadan-puspenerbal-hadiri-penyerahan-monjaya-dan-joy-sailing-kri-bima-suci\/wadan-puspenerbal-hadiri-penyerahan-monjaya\/","title":{"rendered":"Wadan Puspenerbal Hadiri Penyerahan Monjaya"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-199760","attachment","type-attachment","status-inherit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>nawacita<\/title>\n<meta name=\"description\" content=\"nawacita\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"nawacita\" \/>\n<meta property=\"og:description\" content=\"nawacita\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Nawacita\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nawacitaco-1763136813898723\/?ref=aymt_homepage_panel\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@nawacit4\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya.jpg\",\"url\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya.jpg\",\"name\":\"nawacita\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nawacita.co\\\/#website\"},\"datePublished\":\"2024-02-12T10:46:52+00:00\",\"description\":\"nawacita\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nawacita.co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wadan Puspenerbal Hadiri Penyerahan Monjaya dan Joy Sailing KRI Bima Suci\",\"item\":\"https:\\\/\\\/nawacita.co\\\/index.php\\\/2024\\\/02\\\/12\\\/wadan-puspenerbal-hadiri-penyerahan-monjaya-dan-joy-sailing-kri-bima-suci\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wadan Puspenerbal Hadiri Penyerahan Monjaya\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nawacita.co\\\/#website\",\"url\":\"https:\\\/\\\/nawacita.co\\\/\",\"name\":\"Nawacita\",\"description\":\"Berita Kementerian, BUMN, Pemerintah dan Politik\",\"publisher\":{\"@id\":\"https:\\\/\\\/nawacita.co\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nawacita.co\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nawacita.co\\\/#organization\",\"name\":\"Nawacita\",\"url\":\"https:\\\/\\\/nawacita.co\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/nawacita.co\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Logo-Nawacita-2021.png\",\"contentUrl\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Logo-Nawacita-2021.png\",\"width\":1676,\"height\":422,\"caption\":\"Nawacita\"},\"image\":{\"@id\":\"https:\\\/\\\/nawacita.co\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/nawacitaco-1763136813898723\\\/?ref=aymt_homepage_panel\",\"https:\\\/\\\/x.com\\\/nawacit4\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"nawacita","description":"nawacita","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya.jpg","og_locale":"en_US","og_type":"article","og_title":"nawacita","og_description":"nawacita","og_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya.jpg","og_site_name":"Nawacita","article_publisher":"https:\/\/www.facebook.com\/nawacitaco-1763136813898723\/?ref=aymt_homepage_panel","og_image":[{"url":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya.jpg","width":1,"height":1,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@nawacit4","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya.jpg","url":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya.jpg","name":"nawacita","isPartOf":{"@id":"https:\/\/nawacita.co\/#website"},"datePublished":"2024-02-12T10:46:52+00:00","description":"nawacita","breadcrumb":{"@id":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nawacita.co\/"},{"@type":"ListItem","position":2,"name":"Wadan Puspenerbal Hadiri Penyerahan Monjaya dan Joy Sailing KRI Bima Suci","item":"https:\/\/nawacita.co\/index.php\/2024\/02\/12\/wadan-puspenerbal-hadiri-penyerahan-monjaya-dan-joy-sailing-kri-bima-suci\/"},{"@type":"ListItem","position":3,"name":"Wadan Puspenerbal Hadiri Penyerahan Monjaya"}]},{"@type":"WebSite","@id":"https:\/\/nawacita.co\/#website","url":"https:\/\/nawacita.co\/","name":"Nawacita","description":"Berita Kementerian, BUMN, Pemerintah dan Politik","publisher":{"@id":"https:\/\/nawacita.co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nawacita.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/nawacita.co\/#organization","name":"Nawacita","url":"https:\/\/nawacita.co\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nawacita.co\/#\/schema\/logo\/image\/","url":"https:\/\/nawacita.co\/wp-content\/uploads\/2021\/10\/Logo-Nawacita-2021.png","contentUrl":"https:\/\/nawacita.co\/wp-content\/uploads\/2021\/10\/Logo-Nawacita-2021.png","width":1676,"height":422,"caption":"Nawacita"},"image":{"@id":"https:\/\/nawacita.co\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nawacitaco-1763136813898723\/?ref=aymt_homepage_panel","https:\/\/x.com\/nawacit4"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-300x200.jpg 300w, https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-1024x683.jpg 1024w, https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-768x512.jpg 768w, https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-1536x1024.jpg 1536w, https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-696x464.jpg 696w, https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-1068x712.jpg 1068w, https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-630x420.jpg 630w, https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1600,"height":1067,"file":"2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya.jpg","filesize":378833,"sizes":{"medium":{"file":"Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-300x200.jpg","width":300,"height":200,"filesize":19452,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-300x200.jpg"},"large":{"file":"Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-1024x683.jpg","width":1024,"height":683,"filesize":131419,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-1024x683.jpg"},"thumbnail":{"file":"Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-150x150.jpg","width":150,"height":150,"filesize":8701,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-150x150.jpg"},"medium_large":{"file":"Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-768x512.jpg","width":768,"height":512,"filesize":84403,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-768x512.jpg"},"1536x1536":{"file":"Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-1536x1024.jpg","width":1536,"height":1024,"filesize":238967,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-1536x1024.jpg"},"td_218x150":{"file":"Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-218x150.jpg","width":218,"height":150,"filesize":12125,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-218x150.jpg"},"td_324x400":{"file":"Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-324x400.jpg","width":324,"height":400,"filesize":32102,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-324x400.jpg"},"td_485x360":{"file":"Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-485x360.jpg","width":485,"height":360,"filesize":45161,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-485x360.jpg"},"td_696x0":{"file":"Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-696x464.jpg","width":696,"height":464,"filesize":72407,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-696x464.jpg"},"td_1068x0":{"file":"Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-1068x712.jpg","width":1068,"height":712,"filesize":139956,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-1068x712.jpg"},"td_0x420":{"file":"Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-630x420.jpg","width":630,"height":420,"filesize":62723,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-630x420.jpg"},"td_80x60":{"file":"Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-80x60.jpg","width":80,"height":60,"filesize":2885,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-80x60.jpg"},"td_100x70":{"file":"Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-100x70.jpg","width":100,"height":70,"filesize":3839,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-100x70.jpg"},"td_265x198":{"file":"Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-265x198.jpg","width":265,"height":198,"filesize":17582,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-265x198.jpg"},"td_324x160":{"file":"Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-324x160.jpg","width":324,"height":160,"filesize":16930,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-324x160.jpg"},"td_324x235":{"file":"Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-324x235.jpg","width":324,"height":235,"filesize":23770,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-324x235.jpg"},"td_356x220":{"file":"Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-356x220.jpg","width":356,"height":220,"filesize":24225,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-356x220.jpg"},"td_356x364":{"file":"Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-356x364.jpg","width":356,"height":364,"filesize":34013,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-356x364.jpg"},"td_533x261":{"file":"Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-533x261.jpg","width":533,"height":261,"filesize":37506,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-533x261.jpg"},"td_534x462":{"file":"Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-534x462.jpg","width":534,"height":462,"filesize":56876,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-534x462.jpg"},"td_696x385":{"file":"Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-696x385.jpg","width":696,"height":385,"filesize":62952,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-696x385.jpg"},"td_741x486":{"file":"Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-741x486.jpg","width":741,"height":486,"filesize":79157,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-741x486.jpg"},"td_1068x580":{"file":"Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-1068x580.jpg","width":1068,"height":580,"filesize":119697,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya-1068x580.jpg"},"full":{"file":"Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya.jpg","width":1600,"height":1067,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":199756,"source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2024\/02\/Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya.jpg","filename":"Wadan-Puspenerbal-Hadiri-Penyerahan-Monjaya.jpg","filesize":378833,"_links":{"self":[{"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/media\/199760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/comments?post=199760"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":199756,"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/posts\/199756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}