{"id":159584,"date":"2023-02-11T16:56:02","date_gmt":"2023-02-11T09:56:02","guid":{"rendered":"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1.jpg"},"modified":"2023-02-11T16:56:18","modified_gmt":"2023-02-11T09:56:18","slug":"st-valentines_wikimedia-commons_759-1","status":"inherit","type":"attachment","link":"https:\/\/nawacita.co\/index.php\/2023\/02\/11\/sejarah-hari-valentine-kisah-tragis-di-balik-hari-kasih-sayang\/st-valentines_wikimedia-commons_759-1\/","title":{"rendered":"Sejarah Hari Valentine, Asal Usul serta Maknanya."},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-159584","attachment","type-attachment","status-inherit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>nawacita<\/title>\n<meta name=\"description\" content=\"nawacita\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"nawacita\" \/>\n<meta property=\"og:description\" content=\"nawacita\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Nawacita\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nawacitaco-1763136813898723\/?ref=aymt_homepage_panel\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-11T09:56:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"719\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@nawacit4\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/st-valentines_wikimedia-commons_759-1.jpg\",\"url\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/st-valentines_wikimedia-commons_759-1.jpg\",\"name\":\"nawacita\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nawacita.co\\\/#website\"},\"datePublished\":\"2023-02-11T09:56:02+00:00\",\"dateModified\":\"2023-02-11T09:56:18+00:00\",\"description\":\"nawacita\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/st-valentines_wikimedia-commons_759-1.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/st-valentines_wikimedia-commons_759-1.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/st-valentines_wikimedia-commons_759-1.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nawacita.co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sejarah Hari Valentine, Kisah Tragis di Balik Hari Kasih Sayang\",\"item\":\"https:\\\/\\\/nawacita.co\\\/index.php\\\/2023\\\/02\\\/11\\\/sejarah-hari-valentine-kisah-tragis-di-balik-hari-kasih-sayang\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sejarah Hari Valentine, Asal Usul serta Maknanya.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nawacita.co\\\/#website\",\"url\":\"https:\\\/\\\/nawacita.co\\\/\",\"name\":\"Nawacita\",\"description\":\"Berita Kementerian, BUMN, Pemerintah dan Politik\",\"publisher\":{\"@id\":\"https:\\\/\\\/nawacita.co\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nawacita.co\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nawacita.co\\\/#organization\",\"name\":\"Nawacita\",\"url\":\"https:\\\/\\\/nawacita.co\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/nawacita.co\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Logo-Nawacita-2021.png\",\"contentUrl\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Logo-Nawacita-2021.png\",\"width\":1676,\"height\":422,\"caption\":\"Nawacita\"},\"image\":{\"@id\":\"https:\\\/\\\/nawacita.co\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/nawacitaco-1763136813898723\\\/?ref=aymt_homepage_panel\",\"https:\\\/\\\/x.com\\\/nawacit4\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"nawacita","description":"nawacita","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1.jpg","og_locale":"en_US","og_type":"article","og_title":"nawacita","og_description":"nawacita","og_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1.jpg","og_site_name":"Nawacita","article_publisher":"https:\/\/www.facebook.com\/nawacitaco-1763136813898723\/?ref=aymt_homepage_panel","article_modified_time":"2023-02-11T09:56:18+00:00","og_image":[{"width":719,"height":400,"url":"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@nawacit4","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1.jpg","url":"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1.jpg","name":"nawacita","isPartOf":{"@id":"https:\/\/nawacita.co\/#website"},"datePublished":"2023-02-11T09:56:02+00:00","dateModified":"2023-02-11T09:56:18+00:00","description":"nawacita","breadcrumb":{"@id":"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nawacita.co\/"},{"@type":"ListItem","position":2,"name":"Sejarah Hari Valentine, Kisah Tragis di Balik Hari Kasih Sayang","item":"https:\/\/nawacita.co\/index.php\/2023\/02\/11\/sejarah-hari-valentine-kisah-tragis-di-balik-hari-kasih-sayang\/"},{"@type":"ListItem","position":3,"name":"Sejarah Hari Valentine, Asal Usul serta Maknanya."}]},{"@type":"WebSite","@id":"https:\/\/nawacita.co\/#website","url":"https:\/\/nawacita.co\/","name":"Nawacita","description":"Berita Kementerian, BUMN, Pemerintah dan Politik","publisher":{"@id":"https:\/\/nawacita.co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nawacita.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/nawacita.co\/#organization","name":"Nawacita","url":"https:\/\/nawacita.co\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nawacita.co\/#\/schema\/logo\/image\/","url":"https:\/\/nawacita.co\/wp-content\/uploads\/2021\/10\/Logo-Nawacita-2021.png","contentUrl":"https:\/\/nawacita.co\/wp-content\/uploads\/2021\/10\/Logo-Nawacita-2021.png","width":1676,"height":422,"caption":"Nawacita"},"image":{"@id":"https:\/\/nawacita.co\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nawacitaco-1763136813898723\/?ref=aymt_homepage_panel","https:\/\/x.com\/nawacit4"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"167\" src=\"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1-300x167.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1-300x167.jpg 300w, https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1-696x385.jpg 696w, https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1.jpg 719w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Sejarah Hari Valentine, Asal Usul serta Maknanya.<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":719,"height":400,"file":"2023\/02\/st-valentines_wikimedia-commons_759-1.jpg","filesize":60026,"sizes":{"medium":{"file":"st-valentines_wikimedia-commons_759-1-300x167.jpg","width":300,"height":167,"filesize":17733,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1-300x167.jpg"},"thumbnail":{"file":"st-valentines_wikimedia-commons_759-1-150x150.jpg","width":150,"height":150,"filesize":8501,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1-150x150.jpg"},"td_218x150":{"file":"st-valentines_wikimedia-commons_759-1-218x150.jpg","width":218,"height":150,"filesize":12138,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1-218x150.jpg"},"td_324x400":{"file":"st-valentines_wikimedia-commons_759-1-324x400.jpg","width":324,"height":400,"filesize":34572,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1-324x400.jpg"},"td_485x360":{"file":"st-valentines_wikimedia-commons_759-1-485x360.jpg","width":485,"height":360,"filesize":45481,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1-485x360.jpg"},"td_696x0":{"file":"st-valentines_wikimedia-commons_759-1-696x387.jpg","width":696,"height":387,"filesize":69050,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1-696x387.jpg"},"td_80x60":{"file":"st-valentines_wikimedia-commons_759-1-80x60.jpg","width":80,"height":60,"filesize":2681,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1-80x60.jpg"},"td_100x70":{"file":"st-valentines_wikimedia-commons_759-1-100x70.jpg","width":100,"height":70,"filesize":3574,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1-100x70.jpg"},"td_265x198":{"file":"st-valentines_wikimedia-commons_759-1-265x198.jpg","width":265,"height":198,"filesize":17693,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1-265x198.jpg"},"td_324x160":{"file":"st-valentines_wikimedia-commons_759-1-324x160.jpg","width":324,"height":160,"filesize":17760,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1-324x160.jpg"},"td_324x235":{"file":"st-valentines_wikimedia-commons_759-1-324x235.jpg","width":324,"height":235,"filesize":24257,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1-324x235.jpg"},"td_356x220":{"file":"st-valentines_wikimedia-commons_759-1-356x220.jpg","width":356,"height":220,"filesize":25616,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1-356x220.jpg"},"td_356x364":{"file":"st-valentines_wikimedia-commons_759-1-356x364.jpg","width":356,"height":364,"filesize":33421,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1-356x364.jpg"},"td_533x261":{"file":"st-valentines_wikimedia-commons_759-1-533x261.jpg","width":533,"height":261,"filesize":39931,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1-533x261.jpg"},"td_534x462":{"file":"st-valentines_wikimedia-commons_759-1-534x400.jpg","width":534,"height":400,"filesize":58069,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1-534x400.jpg"},"td_696x385":{"file":"st-valentines_wikimedia-commons_759-1-696x385.jpg","width":696,"height":385,"filesize":68108,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1-696x385.jpg"},"full":{"file":"st-valentines_wikimedia-commons_759-1.jpg","width":719,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":159582,"source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2023\/02\/st-valentines_wikimedia-commons_759-1.jpg","_links":{"self":[{"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/media\/159584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/comments?post=159584"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":159582,"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/posts\/159582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}