{"id":152644,"date":"2022-12-02T15:55:53","date_gmt":"2022-12-02T08:55:53","guid":{"rendered":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm.jpg"},"modified":"2022-12-02T15:56:16","modified_gmt":"2022-12-02T08:56:16","slug":"asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm","status":"inherit","type":"attachment","link":"https:\/\/nawacita.co\/index.php\/2022\/12\/02\/israel-dan-amerika-latihan-militer-bersama-siap-hadapi-ancaman-iran\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm\/","title":{"rendered":"Israel dan Amerika Latihan Militer Bersama, Siap Hadapi Ancaman Iran."},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-152644","attachment","type-attachment","status-inherit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>nawacita<\/title>\n<meta name=\"description\" content=\"nawacita\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"nawacita\" \/>\n<meta property=\"og:description\" content=\"nawacita\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Nawacita\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nawacitaco-1763136813898723\/?ref=aymt_homepage_panel\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-02T08:56:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@nawacit4\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm.jpg\",\"url\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm.jpg\",\"name\":\"nawacita\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nawacita.co\\\/#website\"},\"datePublished\":\"2022-12-02T08:55:53+00:00\",\"dateModified\":\"2022-12-02T08:56:16+00:00\",\"description\":\"nawacita\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nawacita.co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Israel dan Amerika Latihan Militer Bersama, Siap Hadapi Ancaman Iran\",\"item\":\"https:\\\/\\\/nawacita.co\\\/index.php\\\/2022\\\/12\\\/02\\\/israel-dan-amerika-latihan-militer-bersama-siap-hadapi-ancaman-iran\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Israel dan Amerika Latihan Militer Bersama, Siap Hadapi Ancaman Iran.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nawacita.co\\\/#website\",\"url\":\"https:\\\/\\\/nawacita.co\\\/\",\"name\":\"Nawacita\",\"description\":\"Berita Kementerian, BUMN, Pemerintah dan Politik\",\"publisher\":{\"@id\":\"https:\\\/\\\/nawacita.co\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nawacita.co\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nawacita.co\\\/#organization\",\"name\":\"Nawacita\",\"url\":\"https:\\\/\\\/nawacita.co\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/nawacita.co\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Logo-Nawacita-2021.png\",\"contentUrl\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Logo-Nawacita-2021.png\",\"width\":1676,\"height\":422,\"caption\":\"Nawacita\"},\"image\":{\"@id\":\"https:\\\/\\\/nawacita.co\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/nawacitaco-1763136813898723\\\/?ref=aymt_homepage_panel\",\"https:\\\/\\\/x.com\\\/nawacit4\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"nawacita","description":"nawacita","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm.jpg","og_locale":"en_US","og_type":"article","og_title":"nawacita","og_description":"nawacita","og_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm.jpg","og_site_name":"Nawacita","article_publisher":"https:\/\/www.facebook.com\/nawacitaco-1763136813898723\/?ref=aymt_homepage_panel","article_modified_time":"2022-12-02T08:56:16+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@nawacit4","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm.jpg","url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm.jpg","name":"nawacita","isPartOf":{"@id":"https:\/\/nawacita.co\/#website"},"datePublished":"2022-12-02T08:55:53+00:00","dateModified":"2022-12-02T08:56:16+00:00","description":"nawacita","breadcrumb":{"@id":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nawacita.co\/"},{"@type":"ListItem","position":2,"name":"Israel dan Amerika Latihan Militer Bersama, Siap Hadapi Ancaman Iran","item":"https:\/\/nawacita.co\/index.php\/2022\/12\/02\/israel-dan-amerika-latihan-militer-bersama-siap-hadapi-ancaman-iran\/"},{"@type":"ListItem","position":3,"name":"Israel dan Amerika Latihan Militer Bersama, Siap Hadapi Ancaman Iran."}]},{"@type":"WebSite","@id":"https:\/\/nawacita.co\/#website","url":"https:\/\/nawacita.co\/","name":"Nawacita","description":"Berita Kementerian, BUMN, Pemerintah dan Politik","publisher":{"@id":"https:\/\/nawacita.co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nawacita.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/nawacita.co\/#organization","name":"Nawacita","url":"https:\/\/nawacita.co\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nawacita.co\/#\/schema\/logo\/image\/","url":"https:\/\/nawacita.co\/wp-content\/uploads\/2021\/10\/Logo-Nawacita-2021.png","contentUrl":"https:\/\/nawacita.co\/wp-content\/uploads\/2021\/10\/Logo-Nawacita-2021.png","width":1676,"height":422,"caption":"Nawacita"},"image":{"@id":"https:\/\/nawacita.co\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nawacitaco-1763136813898723\/?ref=aymt_homepage_panel","https:\/\/x.com\/nawacit4"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"Israel dan Amerika Latihan Militer Bersama\" srcset=\"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm-300x200.jpg 300w, https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Israel dan Amerika Latihan Militer Bersama, Siap Hadapi Ancaman Iran.<\/p>\n"},"alt_text":"Israel dan Amerika Latihan Militer Bersama","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":600,"height":400,"file":"2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm.jpg","filesize":93655,"sizes":{"medium":{"file":"asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm-300x200.jpg","width":300,"height":200,"filesize":19136,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm-300x200.jpg"},"thumbnail":{"file":"asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm-150x150.jpg","width":150,"height":150,"filesize":8512,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm-150x150.jpg"},"td_80x60":{"file":"asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm-80x60.jpg","width":80,"height":60,"filesize":2869,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm-80x60.jpg"},"td_100x70":{"file":"asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm-100x70.jpg","width":100,"height":70,"filesize":3801,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm-100x70.jpg"},"td_218x150":{"file":"asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm-218x150.jpg","width":218,"height":150,"filesize":11774,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm-218x150.jpg"},"td_265x198":{"file":"asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm-265x198.jpg","width":265,"height":198,"filesize":16543,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm-265x198.jpg"},"td_324x160":{"file":"asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm-324x160.jpg","width":324,"height":160,"filesize":14840,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm-324x160.jpg"},"td_324x235":{"file":"asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm-324x235.jpg","width":324,"height":235,"filesize":22074,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm-324x235.jpg"},"td_324x400":{"file":"asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm-324x400.jpg","width":324,"height":400,"filesize":30286,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm-324x400.jpg"},"td_356x220":{"file":"asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm-356x220.jpg","width":356,"height":220,"filesize":22345,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm-356x220.jpg"},"td_356x364":{"file":"asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm-356x364.jpg","width":356,"height":364,"filesize":29618,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm-356x364.jpg"},"td_533x261":{"file":"asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm-533x261.jpg","width":533,"height":261,"filesize":30452,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm-533x261.jpg"},"td_534x462":{"file":"asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm-534x400.jpg","width":534,"height":400,"filesize":48873,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm-534x400.jpg"},"td_696x385":{"file":"asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm-600x385.jpg","width":600,"height":385,"filesize":52864,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm-600x385.jpg"},"full":{"file":"asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm.jpg","width":600,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":152640,"source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/12\/asisrael-bakal-gelar-latihan-bersama-iran-tebar-ancaman-pwm.jpg","_links":{"self":[{"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/media\/152644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/comments?post=152644"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":152640,"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/posts\/152640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}