{"id":151816,"date":"2022-11-22T18:27:02","date_gmt":"2022-11-22T11:27:02","guid":{"rendered":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1.jpg"},"modified":"2022-11-22T18:27:15","modified_gmt":"2022-11-22T11:27:15","slug":"6376c3dc8c52f-denise-chariesta_663_372-1","status":"inherit","type":"attachment","link":"https:\/\/nawacita.co\/index.php\/2022\/11\/22\/viral-foto-syur-mirip-denise-chariesta-dengan-seorang-pria-berinisial-s\/6376c3dc8c52f-denise-chariesta_663_372-1\/","title":{"rendered":"Viral Foto Syur Mirip Denise Chariesta Dengan Seorang Pria Berinisial S"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-151816","attachment","type-attachment","status-inherit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>nawacita<\/title>\n<meta name=\"description\" content=\"nawacita\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"nawacita\" \/>\n<meta property=\"og:description\" content=\"nawacita\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Nawacita\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nawacitaco-1763136813898723\/?ref=aymt_homepage_panel\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-22T11:27:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"712\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@nawacit4\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/6376c3dc8c52f-denise-chariesta_663_372-1.jpg\",\"url\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/6376c3dc8c52f-denise-chariesta_663_372-1.jpg\",\"name\":\"nawacita\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nawacita.co\\\/#website\"},\"datePublished\":\"2022-11-22T11:27:02+00:00\",\"dateModified\":\"2022-11-22T11:27:15+00:00\",\"description\":\"nawacita\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/6376c3dc8c52f-denise-chariesta_663_372-1.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/6376c3dc8c52f-denise-chariesta_663_372-1.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/6376c3dc8c52f-denise-chariesta_663_372-1.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nawacita.co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Viral Foto Syur Mirip Denise Chariesta Dengan Seorang Pria Berinisial S\",\"item\":\"https:\\\/\\\/nawacita.co\\\/index.php\\\/2022\\\/11\\\/22\\\/viral-foto-syur-mirip-denise-chariesta-dengan-seorang-pria-berinisial-s\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Viral Foto Syur Mirip Denise Chariesta Dengan Seorang Pria Berinisial S\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nawacita.co\\\/#website\",\"url\":\"https:\\\/\\\/nawacita.co\\\/\",\"name\":\"Nawacita\",\"description\":\"Berita Kementerian, BUMN, Pemerintah dan Politik\",\"publisher\":{\"@id\":\"https:\\\/\\\/nawacita.co\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nawacita.co\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nawacita.co\\\/#organization\",\"name\":\"Nawacita\",\"url\":\"https:\\\/\\\/nawacita.co\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/nawacita.co\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Logo-Nawacita-2021.png\",\"contentUrl\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Logo-Nawacita-2021.png\",\"width\":1676,\"height\":422,\"caption\":\"Nawacita\"},\"image\":{\"@id\":\"https:\\\/\\\/nawacita.co\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/nawacitaco-1763136813898723\\\/?ref=aymt_homepage_panel\",\"https:\\\/\\\/x.com\\\/nawacit4\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"nawacita","description":"nawacita","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1.jpg","og_locale":"en_US","og_type":"article","og_title":"nawacita","og_description":"nawacita","og_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1.jpg","og_site_name":"Nawacita","article_publisher":"https:\/\/www.facebook.com\/nawacitaco-1763136813898723\/?ref=aymt_homepage_panel","article_modified_time":"2022-11-22T11:27:15+00:00","og_image":[{"width":712,"height":400,"url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@nawacit4","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1.jpg","url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1.jpg","name":"nawacita","isPartOf":{"@id":"https:\/\/nawacita.co\/#website"},"datePublished":"2022-11-22T11:27:02+00:00","dateModified":"2022-11-22T11:27:15+00:00","description":"nawacita","breadcrumb":{"@id":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nawacita.co\/"},{"@type":"ListItem","position":2,"name":"Viral Foto Syur Mirip Denise Chariesta Dengan Seorang Pria Berinisial S","item":"https:\/\/nawacita.co\/index.php\/2022\/11\/22\/viral-foto-syur-mirip-denise-chariesta-dengan-seorang-pria-berinisial-s\/"},{"@type":"ListItem","position":3,"name":"Viral Foto Syur Mirip Denise Chariesta Dengan Seorang Pria Berinisial S"}]},{"@type":"WebSite","@id":"https:\/\/nawacita.co\/#website","url":"https:\/\/nawacita.co\/","name":"Nawacita","description":"Berita Kementerian, BUMN, Pemerintah dan Politik","publisher":{"@id":"https:\/\/nawacita.co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nawacita.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/nawacita.co\/#organization","name":"Nawacita","url":"https:\/\/nawacita.co\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nawacita.co\/#\/schema\/logo\/image\/","url":"https:\/\/nawacita.co\/wp-content\/uploads\/2021\/10\/Logo-Nawacita-2021.png","contentUrl":"https:\/\/nawacita.co\/wp-content\/uploads\/2021\/10\/Logo-Nawacita-2021.png","width":1676,"height":422,"caption":"Nawacita"},"image":{"@id":"https:\/\/nawacita.co\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nawacitaco-1763136813898723\/?ref=aymt_homepage_panel","https:\/\/x.com\/nawacit4"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"Foto Syur Mirip Denise Chariesta\" srcset=\"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1-300x169.jpg 300w, https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1-696x391.jpg 696w, https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1.jpg 712w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Viral Foto Syur Mirip Denise Chariesta Dengan Seorang Pria Berinisial S<\/p>\n"},"alt_text":"Foto Syur Mirip Denise Chariesta","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":712,"height":400,"file":"2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1.jpg","filesize":39527,"sizes":{"medium":{"file":"6376c3dc8c52f-denise-chariesta_663_372-1-300x169.jpg","width":300,"height":169,"filesize":11603,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1-300x169.jpg"},"thumbnail":{"file":"6376c3dc8c52f-denise-chariesta_663_372-1-150x150.jpg","width":150,"height":150,"filesize":5905,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1-150x150.jpg"},"td_80x60":{"file":"6376c3dc8c52f-denise-chariesta_663_372-1-80x60.jpg","width":80,"height":60,"filesize":2503,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1-80x60.jpg"},"td_100x70":{"file":"6376c3dc8c52f-denise-chariesta_663_372-1-100x70.jpg","width":100,"height":70,"filesize":3202,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1-100x70.jpg"},"td_218x150":{"file":"6376c3dc8c52f-denise-chariesta_663_372-1-218x150.jpg","width":218,"height":150,"filesize":8265,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1-218x150.jpg"},"td_265x198":{"file":"6376c3dc8c52f-denise-chariesta_663_372-1-265x198.jpg","width":265,"height":198,"filesize":10853,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1-265x198.jpg"},"td_324x160":{"file":"6376c3dc8c52f-denise-chariesta_663_372-1-324x160.jpg","width":324,"height":160,"filesize":11468,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1-324x160.jpg"},"td_324x235":{"file":"6376c3dc8c52f-denise-chariesta_663_372-1-324x235.jpg","width":324,"height":235,"filesize":14094,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1-324x235.jpg"},"td_324x400":{"file":"6376c3dc8c52f-denise-chariesta_663_372-1-324x400.jpg","width":324,"height":400,"filesize":15939,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1-324x400.jpg"},"td_356x220":{"file":"6376c3dc8c52f-denise-chariesta_663_372-1-356x220.jpg","width":356,"height":220,"filesize":15039,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1-356x220.jpg"},"td_356x364":{"file":"6376c3dc8c52f-denise-chariesta_663_372-1-356x364.jpg","width":356,"height":364,"filesize":17679,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1-356x364.jpg"},"td_533x261":{"file":"6376c3dc8c52f-denise-chariesta_663_372-1-533x261.jpg","width":533,"height":261,"filesize":22392,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1-533x261.jpg"},"td_534x462":{"file":"6376c3dc8c52f-denise-chariesta_663_372-1-534x400.jpg","width":534,"height":400,"filesize":26977,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1-534x400.jpg"},"td_696x0":{"file":"6376c3dc8c52f-denise-chariesta_663_372-1-696x391.jpg","width":696,"height":391,"filesize":35280,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1-696x391.jpg"},"td_696x385":{"file":"6376c3dc8c52f-denise-chariesta_663_372-1-696x385.jpg","width":696,"height":385,"filesize":35063,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1-696x385.jpg"},"full":{"file":"6376c3dc8c52f-denise-chariesta_663_372-1.jpg","width":712,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":151815,"source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/11\/6376c3dc8c52f-denise-chariesta_663_372-1.jpg","filename":"6376c3dc8c52f-denise-chariesta_663_372-1.jpg","filesize":39527,"_links":{"self":[{"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/media\/151816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/comments?post=151816"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":151815,"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/posts\/151815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}