{"id":144759,"date":"2022-09-03T10:00:24","date_gmt":"2022-09-03T03:00:24","guid":{"rendered":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43.jpeg"},"modified":"2022-09-03T10:00:55","modified_gmt":"2022-09-03T03:00:55","slug":"mensos-tri-rismaharini-rizky-detikcom_43","status":"inherit","type":"attachment","link":"https:\/\/nawacita.co\/index.php\/2022\/09\/03\/kemensos-gunakan-data-blt-minyak-goreng-untuk-salurkan-blt-bbm\/mensos-tri-rismaharini-rizky-detikcom_43\/","title":{"rendered":"Kemensos Gunakan Data BLT Minyak Goreng untuk Salurkan BLT BBM"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-144759","attachment","type-attachment","status-inherit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>nawacita<\/title>\n<meta name=\"description\" content=\"nawacita\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43.jpeg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"nawacita\" \/>\n<meta property=\"og:description\" content=\"nawacita\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43.jpeg\" \/>\n<meta property=\"og:site_name\" content=\"Nawacita\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nawacitaco-1763136813898723\/?ref=aymt_homepage_panel\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-03T03:00:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@nawacit4\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/mensos-tri-rismaharini-rizky-detikcom_43.jpeg\",\"url\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/mensos-tri-rismaharini-rizky-detikcom_43.jpeg\",\"name\":\"nawacita\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nawacita.co\\\/#website\"},\"datePublished\":\"2022-09-03T03:00:24+00:00\",\"dateModified\":\"2022-09-03T03:00:55+00:00\",\"description\":\"nawacita\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/mensos-tri-rismaharini-rizky-detikcom_43.jpeg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/mensos-tri-rismaharini-rizky-detikcom_43.jpeg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/mensos-tri-rismaharini-rizky-detikcom_43.jpeg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nawacita.co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kemensos Gunakan Data BLT Minyak Goreng untuk Salurkan BLT BBM\",\"item\":\"https:\\\/\\\/nawacita.co\\\/index.php\\\/2022\\\/09\\\/03\\\/kemensos-gunakan-data-blt-minyak-goreng-untuk-salurkan-blt-bbm\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kemensos Gunakan Data BLT Minyak Goreng untuk Salurkan BLT BBM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nawacita.co\\\/#website\",\"url\":\"https:\\\/\\\/nawacita.co\\\/\",\"name\":\"Nawacita\",\"description\":\"Berita Kementerian, BUMN, Pemerintah dan Politik\",\"publisher\":{\"@id\":\"https:\\\/\\\/nawacita.co\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nawacita.co\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nawacita.co\\\/#organization\",\"name\":\"Nawacita\",\"url\":\"https:\\\/\\\/nawacita.co\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/nawacita.co\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Logo-Nawacita-2021.png\",\"contentUrl\":\"https:\\\/\\\/nawacita.co\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Logo-Nawacita-2021.png\",\"width\":1676,\"height\":422,\"caption\":\"Nawacita\"},\"image\":{\"@id\":\"https:\\\/\\\/nawacita.co\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/nawacitaco-1763136813898723\\\/?ref=aymt_homepage_panel\",\"https:\\\/\\\/x.com\\\/nawacit4\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"nawacita","description":"nawacita","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43.jpeg","og_locale":"en_US","og_type":"article","og_title":"nawacita","og_description":"nawacita","og_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43.jpeg","og_site_name":"Nawacita","article_publisher":"https:\/\/www.facebook.com\/nawacitaco-1763136813898723\/?ref=aymt_homepage_panel","article_modified_time":"2022-09-03T03:00:55+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@nawacit4","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43.jpeg","url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43.jpeg","name":"nawacita","isPartOf":{"@id":"https:\/\/nawacita.co\/#website"},"datePublished":"2022-09-03T03:00:24+00:00","dateModified":"2022-09-03T03:00:55+00:00","description":"nawacita","breadcrumb":{"@id":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43.jpeg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43.jpeg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43.jpeg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nawacita.co\/"},{"@type":"ListItem","position":2,"name":"Kemensos Gunakan Data BLT Minyak Goreng untuk Salurkan BLT BBM","item":"https:\/\/nawacita.co\/index.php\/2022\/09\/03\/kemensos-gunakan-data-blt-minyak-goreng-untuk-salurkan-blt-bbm\/"},{"@type":"ListItem","position":3,"name":"Kemensos Gunakan Data BLT Minyak Goreng untuk Salurkan BLT BBM"}]},{"@type":"WebSite","@id":"https:\/\/nawacita.co\/#website","url":"https:\/\/nawacita.co\/","name":"Nawacita","description":"Berita Kementerian, BUMN, Pemerintah dan Politik","publisher":{"@id":"https:\/\/nawacita.co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nawacita.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/nawacita.co\/#organization","name":"Nawacita","url":"https:\/\/nawacita.co\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nawacita.co\/#\/schema\/logo\/image\/","url":"https:\/\/nawacita.co\/wp-content\/uploads\/2021\/10\/Logo-Nawacita-2021.png","contentUrl":"https:\/\/nawacita.co\/wp-content\/uploads\/2021\/10\/Logo-Nawacita-2021.png","width":1676,"height":422,"caption":"Nawacita"},"image":{"@id":"https:\/\/nawacita.co\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nawacitaco-1763136813898723\/?ref=aymt_homepage_panel","https:\/\/x.com\/nawacit4"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43-300x225.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43-300x225.jpeg 300w, https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43-80x60.jpeg 80w, https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43-265x198.jpeg 265w, https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43-696x522.jpeg 696w, https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43-560x420.jpeg 560w, https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43.jpeg 700w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Kemensos Gunakan Data BLT Minyak Goreng untuk Salurkan BLT BBM<\/p>\n"},"caption":{"rendered":"<p>Kemensos Gunakan Data BLT Minyak Goreng untuk Salurkan BLT BBM<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":700,"height":525,"file":"2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43.jpeg","filesize":88603,"sizes":{"medium":{"file":"mensos-tri-rismaharini-rizky-detikcom_43-300x225.jpeg","width":300,"height":225,"filesize":18315,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43-300x225.jpeg"},"thumbnail":{"file":"mensos-tri-rismaharini-rizky-detikcom_43-150x150.jpeg","width":150,"height":150,"filesize":7643,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43-150x150.jpeg"},"td_80x60":{"file":"mensos-tri-rismaharini-rizky-detikcom_43-80x60.jpeg","width":80,"height":60,"filesize":2725,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43-80x60.jpeg"},"td_100x70":{"file":"mensos-tri-rismaharini-rizky-detikcom_43-100x70.jpeg","width":100,"height":70,"filesize":3528,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43-100x70.jpeg"},"td_218x150":{"file":"mensos-tri-rismaharini-rizky-detikcom_43-218x150.jpeg","width":218,"height":150,"filesize":10563,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43-218x150.jpeg"},"td_265x198":{"file":"mensos-tri-rismaharini-rizky-detikcom_43-265x198.jpeg","width":265,"height":198,"filesize":15177,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43-265x198.jpeg"},"td_324x160":{"file":"mensos-tri-rismaharini-rizky-detikcom_43-324x160.jpeg","width":324,"height":160,"filesize":14443,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43-324x160.jpeg"},"td_324x235":{"file":"mensos-tri-rismaharini-rizky-detikcom_43-324x235.jpeg","width":324,"height":235,"filesize":20001,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43-324x235.jpeg"},"td_324x400":{"file":"mensos-tri-rismaharini-rizky-detikcom_43-324x400.jpeg","width":324,"height":400,"filesize":25036,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43-324x400.jpeg"},"td_356x220":{"file":"mensos-tri-rismaharini-rizky-detikcom_43-356x220.jpeg","width":356,"height":220,"filesize":19930,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43-356x220.jpeg"},"td_356x364":{"file":"mensos-tri-rismaharini-rizky-detikcom_43-356x364.jpeg","width":356,"height":364,"filesize":27613,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43-356x364.jpeg"},"td_533x261":{"file":"mensos-tri-rismaharini-rizky-detikcom_43-533x261.jpeg","width":533,"height":261,"filesize":29845,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43-533x261.jpeg"},"td_534x462":{"file":"mensos-tri-rismaharini-rizky-detikcom_43-534x462.jpeg","width":534,"height":462,"filesize":45173,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43-534x462.jpeg"},"td_696x0":{"file":"mensos-tri-rismaharini-rizky-detikcom_43-696x522.jpeg","width":696,"height":522,"filesize":61124,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43-696x522.jpeg"},"td_696x385":{"file":"mensos-tri-rismaharini-rizky-detikcom_43-696x385.jpeg","width":696,"height":385,"filesize":47626,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43-696x385.jpeg"},"td_741x486":{"file":"mensos-tri-rismaharini-rizky-detikcom_43-700x486.jpeg","width":700,"height":486,"filesize":69920,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43-700x486.jpeg"},"td_0x420":{"file":"mensos-tri-rismaharini-rizky-detikcom_43-560x420.jpeg","width":560,"height":420,"filesize":45013,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43-560x420.jpeg"},"full":{"file":"mensos-tri-rismaharini-rizky-detikcom_43.jpeg","width":700,"height":525,"mime_type":"image\/jpeg","source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":144757,"source_url":"https:\/\/nawacita.co\/wp-content\/uploads\/2022\/09\/mensos-tri-rismaharini-rizky-detikcom_43.jpeg","filename":"mensos-tri-rismaharini-rizky-detikcom_43.jpeg","filesize":88603,"_links":{"self":[{"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/media\/144759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/comments?post=144759"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":144757,"href":"https:\/\/nawacita.co\/index.php\/wp-json\/wp\/v2\/posts\/144757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}